{"id":351,"date":"2020-09-15T10:16:07","date_gmt":"2020-09-15T08:16:07","guid":{"rendered":"http:\/\/escaudacienne.fr\/esc\/?page_id=351"},"modified":"2024-08-07T11:24:21","modified_gmt":"2024-08-07T09:24:21","slug":"sections","status":"publish","type":"page","link":"https:\/\/escaudacienne.fr\/esc\/sections\/","title":{"rendered":"SECTIONS"},"content":{"rendered":"\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1335161508\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"413\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/05\/Bandeau-sections-2023-1400x567.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/05\/Bandeau-sections-2023-1400x567.jpg 1400w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/05\/Bandeau-sections-2023-800x324.jpg 800w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/05\/Bandeau-sections-2023-768x311.jpg 768w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/05\/Bandeau-sections-2023-1536x622.jpg 1536w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/05\/Bandeau-sections-2023-510x207.jpg 510w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/05\/Bandeau-sections-2023.jpg 1817w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1335161508 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"gap-1200647414\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1200647414 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >20 Sections et pr\u00e8s de 40 activit\u00e9s... Trouvez celle(s) qui vous convient !<\/span><b><\/b><\/h3><\/div>\n\n<div class=\"row align-center\"  id=\"row-808164967\">\n\n\n\t<div id=\"col-1448198349\" class=\"col medium-5 small-12 large-5\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row\"  id=\"row-1162601975\">\n\n\n\t<div id=\"col-1310891546\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1480479136\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/athletisme\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Athletisme-800x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Athletisme-800x800.png 800w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Athletisme-400x400.png 400w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Athletisme-280x280.png 280w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Athletisme-768x768.png 768w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Athletisme-1536x1536.png 1536w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Athletisme-2048x2048.png 2048w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Athletisme-510x510.png 510w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Athletisme-100x100.png 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1480479136 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1045416630\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1814099305\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/badminton\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"473\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Badminton-cercle-4x4-1.png\" class=\"attachment-large size-large\" alt=\"Logo ESC Badminton\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Badminton-cercle-4x4-1.png 472w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Badminton-cercle-4x4-1-399x400.png 399w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Badminton-cercle-4x4-1-280x280.png 280w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Badminton-cercle-4x4-1-100x100.png 100w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1814099305 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-211046492\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1897361537\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/boxe-francaise\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"473\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Boxe-cercle-4x4-1.png\" class=\"attachment-large size-large\" alt=\"Logo ESC Boxe Fran\u00e7aise et Savate Forme\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Boxe-cercle-4x4-1.png 472w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Boxe-cercle-4x4-1-399x400.png 399w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Boxe-cercle-4x4-1-280x280.png 280w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Boxe-cercle-4x4-1-100x100.png 100w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1897361537 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1661756892\" class=\"col medium-5 small-12 large-5\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row\"  id=\"row-1374182428\">\n\n\n\t<div id=\"col-1553190732\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1827691967\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/escalade\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"763\" height=\"800\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2021\/04\/Logo-ESC\u00ae-Escalade-20x20-1-763x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2021\/04\/Logo-ESC\u00ae-Escalade-20x20-1-763x800.png 763w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2021\/04\/Logo-ESC\u00ae-Escalade-20x20-1-381x400.png 381w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2021\/04\/Logo-ESC\u00ae-Escalade-20x20-1-768x805.png 768w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2021\/04\/Logo-ESC\u00ae-Escalade-20x20-1-1465x1536.png 1465w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2021\/04\/Logo-ESC\u00ae-Escalade-20x20-1-1953x2048.png 1953w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2021\/04\/Logo-ESC\u00ae-Escalade-20x20-1-510x535.png 510w\" sizes=\"auto, (max-width: 763px) 100vw, 763px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1827691967 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-696911191\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1471155232\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/escrime-artistique\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"474\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Escrime-cercle-4x4-1.png\" class=\"attachment-large size-large\" alt=\"Logo ESC Escrime Artistique\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Escrime-cercle-4x4-1.png 472w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Escrime-cercle-4x4-1-398x400.png 398w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Escrime-cercle-4x4-1-280x280.png 280w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Escrime-cercle-4x4-1-100x100.png 100w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1471155232 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-549667199\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1016854843\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/baby-omnisport\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"236\" height=\"239\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/02\/Logo-ESC\u00ae-Eveil-Omnisports-2x2-1.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/02\/Logo-ESC\u00ae-Eveil-Omnisports-2x2-1.png 236w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/02\/Logo-ESC\u00ae-Eveil-Omnisports-2x2-1-100x100.png 100w\" sizes=\"auto, (max-width: 236px) 100vw, 236px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1016854843 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-center\"  id=\"row-1768657749\">\n\n\n\t<div id=\"col-1623162149\" class=\"col medium-5 small-12 large-5\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row\"  id=\"row-584282556\">\n\n\n\t<div id=\"col-281733515\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1029629157\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/fitness-dance\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"800\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Fitness-Dance-799x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Fitness-Dance-799x800.png 799w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Fitness-Dance-399x400.png 399w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Fitness-Dance-280x280.png 280w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Fitness-Dance-768x769.png 768w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Fitness-Dance-1534x1536.png 1534w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Fitness-Dance-2045x2048.png 2045w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Fitness-Dance-510x511.png 510w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Fitness-Dance-100x100.png 100w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1029629157 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-451684488\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_220329113\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/football\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"796\" height=\"800\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Football-796x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Football-796x800.png 796w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Football-398x400.png 398w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Football-280x280.png 280w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Football-768x772.png 768w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Football-1528x1536.png 1528w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Football-510x513.png 510w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Football-100x100.png 100w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Football.png 1604w\" sizes=\"auto, (max-width: 796px) 100vw, 796px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_220329113 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-473528806\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1256618274\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/football-americain\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Foot-US-800x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Foot-US-800x800.png 800w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Foot-US-400x400.png 400w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Foot-US-280x280.png 280w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Foot-US-768x768.png 768w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Foot-US-1536x1536.png 1536w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Foot-US-2048x2048.png 2048w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Foot-US-510x510.png 510w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Foot-US-100x100.png 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1256618274 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-897419387\" class=\"col medium-5 small-12 large-5\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row\"  id=\"row-1745922600\">\n\n\n\t<div id=\"col-353617699\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1791330205\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/handball\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Handball-800x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Handball-800x800.png 800w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Handball-400x400.png 400w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Handball-280x280.png 280w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Handball-768x768.png 768w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Handball-1536x1536.png 1536w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Handball-2048x2048.png 2048w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Handball-510x510.png 510w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Handball-100x100.png 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1791330205 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-212188691\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2052534115\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/judo\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Judo-800x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Judo-800x800.png 800w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Judo-400x400.png 400w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Judo-280x280.png 280w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Judo-768x768.png 768w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Judo-1536x1536.png 1536w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Judo-2048x2048.png 2048w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Judo-510x510.png 510w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Judo-100x100.png 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_2052534115 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-533122814\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_171403712\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/karate\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Karate-800x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Karate-800x800.png 800w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Karate-400x400.png 400w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Karate-280x280.png 280w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Karate-768x768.png 768w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Karate-1536x1536.png 1536w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Karate-2048x2048.png 2048w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Karate-510x510.png 510w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Karate-100x100.png 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_171403712 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-center\"  id=\"row-474281410\">\n\n\n\t<div id=\"col-1909862341\" class=\"col medium-5 small-12 large-5\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row\"  id=\"row-72638323\">\n\n\n\t<div id=\"col-271352477\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1596252652\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/mma\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"709\" height=\"709\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2024\/05\/Logo-ESC\u00ae-MMA-6x6-1.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2024\/05\/Logo-ESC\u00ae-MMA-6x6-1.png 709w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2024\/05\/Logo-ESC\u00ae-MMA-6x6-1-400x400.png 400w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2024\/05\/Logo-ESC\u00ae-MMA-6x6-1-280x280.png 280w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2024\/05\/Logo-ESC\u00ae-MMA-6x6-1-510x510.png 510w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2024\/05\/Logo-ESC\u00ae-MMA-6x6-1-100x100.png 100w\" sizes=\"auto, (max-width: 709px) 100vw, 709px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1596252652 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-829587361\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_808352579\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/taekwondo\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Tae-Kwon-Do-800x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Tae-Kwon-Do-800x800.png 800w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Tae-Kwon-Do-400x400.png 400w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Tae-Kwon-Do-280x280.png 280w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Tae-Kwon-Do-768x768.png 768w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Tae-Kwon-Do-1536x1536.png 1536w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Tae-Kwon-Do-2048x2048.png 2048w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Tae-Kwon-Do-510x510.png 510w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Tae-Kwon-Do-100x100.png 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_808352579 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1073590116\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1706722927\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/tennis\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"709\" height=\"709\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/08\/Logo-ESC\u00ae-Tennis-2023-6x6-1.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/08\/Logo-ESC\u00ae-Tennis-2023-6x6-1.png 709w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/08\/Logo-ESC\u00ae-Tennis-2023-6x6-1-400x400.png 400w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/08\/Logo-ESC\u00ae-Tennis-2023-6x6-1-280x280.png 280w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/08\/Logo-ESC\u00ae-Tennis-2023-6x6-1-510x510.png 510w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/08\/Logo-ESC\u00ae-Tennis-2023-6x6-1-100x100.png 100w\" sizes=\"auto, (max-width: 709px) 100vw, 709px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1706722927 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-670404300\" class=\"col medium-5 small-12 large-5\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row\"  id=\"row-864909599\">\n\n\n\t<div id=\"col-1112817029\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_638200103\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/tir-a-larc\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Tir-a-lArc-800x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Tir-a-lArc-800x800.png 800w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Tir-a-lArc-400x400.png 400w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Tir-a-lArc-280x280.png 280w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Tir-a-lArc-768x768.png 768w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Tir-a-lArc-1536x1536.png 1536w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Tir-a-lArc-2048x2048.png 2048w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Tir-a-lArc-510x510.png 510w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Tir-a-lArc-100x100.png 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_638200103 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1917946221\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1361910311\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/velo\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/03\/Logo-ESC\u00ae-Velo-20x20-1-800x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/03\/Logo-ESC\u00ae-Velo-20x20-1-800x800.png 800w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/03\/Logo-ESC\u00ae-Velo-20x20-1-400x400.png 400w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/03\/Logo-ESC\u00ae-Velo-20x20-1-280x280.png 280w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/03\/Logo-ESC\u00ae-Velo-20x20-1-768x768.png 768w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/03\/Logo-ESC\u00ae-Velo-20x20-1-1536x1536.png 1536w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/03\/Logo-ESC\u00ae-Velo-20x20-1-2048x2048.png 2048w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/03\/Logo-ESC\u00ae-Velo-20x20-1-510x510.png 510w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/03\/Logo-ESC\u00ae-Velo-20x20-1-100x100.png 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1361910311 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1652710811\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1613800783\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/volley-ball\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Volley-Ball-800x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Volley-Ball-800x800.png 800w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Volley-Ball-400x400.png 400w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Volley-Ball-280x280.png 280w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Volley-Ball-768x768.png 768w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Volley-Ball-1536x1536.png 1536w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Volley-Ball-2048x2048.png 2048w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Volley-Ball-510x510.png 510w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Volley-Ball-100x100.png 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1613800783 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-center\"  id=\"row-651205760\">\n\n\n\t<div id=\"col-93728571\" class=\"col medium-5 small-12 large-5\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row\"  id=\"row-833111685\">\n\n\n\t<div id=\"col-1156539753\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1227953561\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1017344701\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_601129437\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/vovinam\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Vovinam-800x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Vovinam-800x800.png 800w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Vovinam-400x400.png 400w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Vovinam-280x280.png 280w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Vovinam-768x768.png 768w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Vovinam-1536x1536.png 1536w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Vovinam-2048x2048.png 2048w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Vovinam-510x510.png 510w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Vovinam-100x100.png 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_601129437 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-323952885\" class=\"col medium-5 small-12 large-5\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row\"  id=\"row-418711684\">\n\n\n\t<div id=\"col-1047228395\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_848857342\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/sport-sante\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/03\/Logo-ESC\u00ae-MSS-800x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/03\/Logo-ESC\u00ae-MSS-800x800.png 800w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/03\/Logo-ESC\u00ae-MSS-400x400.png 400w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/03\/Logo-ESC\u00ae-MSS-280x280.png 280w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/03\/Logo-ESC\u00ae-MSS-768x768.png 768w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/03\/Logo-ESC\u00ae-MSS-1536x1536.png 1536w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/03\/Logo-ESC\u00ae-MSS-2048x2048.png 2048w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/03\/Logo-ESC\u00ae-MSS-510x510.png 510w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/03\/Logo-ESC\u00ae-MSS-100x100.png 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_848857342 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-394337462\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1923440369\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-435633930\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-435633930 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1980851399\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"101\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2024\/08\/Les-sections-Baby-V2-1400x139.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2024\/08\/Les-sections-Baby-V2-1400x139.png 1400w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2024\/08\/Les-sections-Baby-V2-800x80.png 800w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2024\/08\/Les-sections-Baby-V2-768x76.png 768w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2024\/08\/Les-sections-Baby-V2-1536x153.png 1536w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2024\/08\/Les-sections-Baby-V2-2048x204.png 2048w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2024\/08\/Les-sections-Baby-V2-510x51.png 510w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1980851399 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"gap-2052422364\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2052422364 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row\"  id=\"row-1071893924\">\n\n\n\t<div id=\"col-688355644\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row\"  id=\"row-982275831\">\n\n\n\t<div id=\"col-1072884803\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_217008788\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/athletisme\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"473\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Athletisme-cercle-4x4-1.png\" class=\"attachment-large size-large\" alt=\"Logo ESC Athl\u00e9tisme\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Athletisme-cercle-4x4-1.png 472w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Athletisme-cercle-4x4-1-399x400.png 399w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Athletisme-cercle-4x4-1-280x280.png 280w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Athletisme-cercle-4x4-1-100x100.png 100w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_217008788 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-734954629\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2050881450\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/baby-omnisport\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"236\" height=\"239\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/02\/Logo-ESC\u00ae-Eveil-Omnisports-2x2-1.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/02\/Logo-ESC\u00ae-Eveil-Omnisports-2x2-1.png 236w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/02\/Logo-ESC\u00ae-Eveil-Omnisports-2x2-1-100x100.png 100w\" sizes=\"auto, (max-width: 236px) 100vw, 236px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_2050881450 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-143111036\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row\"  id=\"row-619008953\">\n\n\n\t<div id=\"col-1041909016\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1067441151\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/football\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"476\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Football-cercle-4x4-1.png\" class=\"attachment-large size-large\" alt=\"Logo ESC Football\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Football-cercle-4x4-1.png 472w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Football-cercle-4x4-1-397x400.png 397w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Football-cercle-4x4-1-100x100.png 100w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1067441151 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2030958592\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2096227289\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/handball\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"473\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Handball-cercle-4x4-1.png\" class=\"attachment-large size-large\" alt=\"Logo ESC Handball\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Handball-cercle-4x4-1.png 472w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Handball-cercle-4x4-1-399x400.png 399w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Handball-cercle-4x4-1-280x280.png 280w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Handball-cercle-4x4-1-100x100.png 100w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_2096227289 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1971705854\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row\"  id=\"row-442540357\">\n\n\n\t<div id=\"col-720138670\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_90853740\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/karate\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"473\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Karate-cercle-4x4-1.png\" class=\"attachment-large size-large\" alt=\"Logo ESC Karat\u00e9\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Karate-cercle-4x4-1.png 472w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Karate-cercle-4x4-1-399x400.png 399w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Karate-cercle-4x4-1-280x280.png 280w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2020\/10\/Logo-ESC\u00ae-Karate-cercle-4x4-1-100x100.png 100w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_90853740 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1655939538\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_235884939\">\n\t\t<a class=\"\" href=\"https:\/\/escaudacienne.fr\/esc\/sections\/tennis\/\"  >\t\t\t\t\t\t<div class=\"img-inner image-grayscale dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"709\" height=\"709\" src=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/08\/Logo-ESC\u00ae-Tennis-2023-6x6-3.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/08\/Logo-ESC\u00ae-Tennis-2023-6x6-3.png 709w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/08\/Logo-ESC\u00ae-Tennis-2023-6x6-3-400x400.png 400w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/08\/Logo-ESC\u00ae-Tennis-2023-6x6-3-280x280.png 280w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/08\/Logo-ESC\u00ae-Tennis-2023-6x6-3-510x510.png 510w, https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2023\/08\/Logo-ESC\u00ae-Tennis-2023-6x6-3-100x100.png 100w\" sizes=\"auto, (max-width: 709px) 100vw, 709px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_235884939 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1970,"featured_media":0,"parent":0,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-351","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.2.1 (Yoast SEO v24.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SECTIONS - ESC - Entente Sportive Caudacienne\u00ae<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/escaudacienne.fr\/esc\/sections\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SECTIONS\" \/>\n<meta property=\"og:url\" content=\"http:\/\/escaudacienne.fr\/esc\/sections\/\" \/>\n<meta property=\"og:site_name\" content=\"ESC - Entente Sportive Caudacienne\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ententesportivecaudacienne\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-07T09:24:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/escaudacienne.fr\/esc\/sections\/\",\"url\":\"http:\/\/escaudacienne.fr\/esc\/sections\/\",\"name\":\"SECTIONS - ESC - Entente Sportive Caudacienne\u00ae\",\"isPartOf\":{\"@id\":\"https:\/\/escaudacienne.fr\/esc\/#website\"},\"datePublished\":\"2020-09-15T08:16:07+00:00\",\"dateModified\":\"2024-08-07T09:24:21+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/escaudacienne.fr\/esc\/sections\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/escaudacienne.fr\/esc\/sections\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/escaudacienne.fr\/esc\/sections\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/escaudacienne.fr\/esc\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SECTIONS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/escaudacienne.fr\/esc\/#website\",\"url\":\"https:\/\/escaudacienne.fr\/esc\/\",\"name\":\"ESC - Entente Sportive Caudacienne\u00ae\",\"description\":\"Faire du Sport \u00e0 La Queue-en-Brie... c&#039;est facile avec l&#039;E.S.C.\u00ae !\",\"publisher\":{\"@id\":\"https:\/\/escaudacienne.fr\/esc\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/escaudacienne.fr\/esc\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/escaudacienne.fr\/esc\/#organization\",\"name\":\"E.S.C.\u00ae - Entente Sportive Caudacienne\u00ae\",\"url\":\"https:\/\/escaudacienne.fr\/esc\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/escaudacienne.fr\/esc\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2021\/01\/Logo-ESC\u00ae-Rouge-Blanc-1968-5x5-1.png\",\"contentUrl\":\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2021\/01\/Logo-ESC\u00ae-Rouge-Blanc-1968-5x5-1.png\",\"width\":591,\"height\":591,\"caption\":\"E.S.C.\u00ae - Entente Sportive Caudacienne\u00ae\"},\"image\":{\"@id\":\"https:\/\/escaudacienne.fr\/esc\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ententesportivecaudacienne\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SECTIONS - ESC - Entente Sportive Caudacienne\u00ae","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/escaudacienne.fr\/esc\/sections\/","og_locale":"fr_FR","og_type":"article","og_title":"SECTIONS","og_url":"http:\/\/escaudacienne.fr\/esc\/sections\/","og_site_name":"ESC - Entente Sportive Caudacienne\u00ae","article_publisher":"https:\/\/www.facebook.com\/ententesportivecaudacienne","article_modified_time":"2024-08-07T09:24:21+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/escaudacienne.fr\/esc\/sections\/","url":"http:\/\/escaudacienne.fr\/esc\/sections\/","name":"SECTIONS - ESC - Entente Sportive Caudacienne\u00ae","isPartOf":{"@id":"https:\/\/escaudacienne.fr\/esc\/#website"},"datePublished":"2020-09-15T08:16:07+00:00","dateModified":"2024-08-07T09:24:21+00:00","breadcrumb":{"@id":"http:\/\/escaudacienne.fr\/esc\/sections\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/escaudacienne.fr\/esc\/sections\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/escaudacienne.fr\/esc\/sections\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/escaudacienne.fr\/esc\/"},{"@type":"ListItem","position":2,"name":"SECTIONS"}]},{"@type":"WebSite","@id":"https:\/\/escaudacienne.fr\/esc\/#website","url":"https:\/\/escaudacienne.fr\/esc\/","name":"ESC - Entente Sportive Caudacienne\u00ae","description":"Faire du Sport \u00e0 La Queue-en-Brie... c&#039;est facile avec l&#039;E.S.C.\u00ae !","publisher":{"@id":"https:\/\/escaudacienne.fr\/esc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/escaudacienne.fr\/esc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/escaudacienne.fr\/esc\/#organization","name":"E.S.C.\u00ae - Entente Sportive Caudacienne\u00ae","url":"https:\/\/escaudacienne.fr\/esc\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/escaudacienne.fr\/esc\/#\/schema\/logo\/image\/","url":"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2021\/01\/Logo-ESC\u00ae-Rouge-Blanc-1968-5x5-1.png","contentUrl":"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2021\/01\/Logo-ESC\u00ae-Rouge-Blanc-1968-5x5-1.png","width":591,"height":591,"caption":"E.S.C.\u00ae - Entente Sportive Caudacienne\u00ae"},"image":{"@id":"https:\/\/escaudacienne.fr\/esc\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ententesportivecaudacienne"]}]}},"_links":{"self":[{"href":"https:\/\/escaudacienne.fr\/esc\/wp-json\/wp\/v2\/pages\/351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/escaudacienne.fr\/esc\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/escaudacienne.fr\/esc\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/escaudacienne.fr\/esc\/wp-json\/wp\/v2\/users\/1970"}],"replies":[{"embeddable":true,"href":"https:\/\/escaudacienne.fr\/esc\/wp-json\/wp\/v2\/comments?post=351"}],"version-history":[{"count":97,"href":"https:\/\/escaudacienne.fr\/esc\/wp-json\/wp\/v2\/pages\/351\/revisions"}],"predecessor-version":[{"id":25636,"href":"https:\/\/escaudacienne.fr\/esc\/wp-json\/wp\/v2\/pages\/351\/revisions\/25636"}],"wp:attachment":[{"href":"https:\/\/escaudacienne.fr\/esc\/wp-json\/wp\/v2\/media?parent=351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}