{"id":13396,"date":"2022-01-03T13:16:14","date_gmt":"2022-01-03T12:16:14","guid":{"rendered":"http:\/\/escaudacienne.fr\/esc\/?p=13396"},"modified":"2022-01-03T13:25:07","modified_gmt":"2022-01-03T12:25:07","slug":"eso-clinique-17","status":"publish","type":"post","link":"https:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/","title":{"rendered":"Eso Clinique"},"content":{"rendered":"\n\n\n<a href=\"http:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2022\/01\/GONCALVES_Thomas_Flyer-3-1.pdf\" target=\"_self\" class=\"button success is-shade is-larger box-shadow-4 box-shadow-5-hover expand\"  style=\"border-radius:6px;\">\n    <span>Affiche fumeurs....<\/span>\n  <\/a>\n\n\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1970,"featured_media":13397,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"chat","meta":{"footnotes":""},"categories":[91,87],"tags":[],"class_list":["post-13396","post","type-post","status-publish","format-chat","has-post-thumbnail","hentry","category-partenaires","category-sport-sante","post_format-post-format-chat"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.2.1 (Yoast SEO v24.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Eso Clinique - ESC - Entente Sportive Caudacienne\u00ae<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eso Clinique\" \/>\n<meta property=\"og:url\" content=\"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/\" \/>\n<meta property=\"og:site_name\" content=\"ESC - Entente Sportive Caudacienne\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ententesportivecaudacienne\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-03T12:16:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-03T12:25:07+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2022\/01\/Affiche-eso-paris-fumeurs-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1810\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"maya2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"maya2\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/\"},\"author\":{\"name\":\"maya2\",\"@id\":\"https:\/\/escaudacienne.fr\/esc\/#\/schema\/person\/829f2ee7197e9e983e17b2c0556f8a77\"},\"headline\":\"Eso Clinique\",\"datePublished\":\"2022-01-03T12:16:14+00:00\",\"dateModified\":\"2022-01-03T12:25:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/\"},\"wordCount\":31,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/escaudacienne.fr\/esc\/#organization\"},\"image\":{\"@id\":\"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2022\/01\/Affiche-eso-paris-fumeurs-scaled.jpg\",\"articleSection\":[\"Partenaires\",\"Sport-Sant\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/\",\"url\":\"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/\",\"name\":\"Eso Clinique - ESC - Entente Sportive Caudacienne\u00ae\",\"isPartOf\":{\"@id\":\"https:\/\/escaudacienne.fr\/esc\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2022\/01\/Affiche-eso-paris-fumeurs-scaled.jpg\",\"datePublished\":\"2022-01-03T12:16:14+00:00\",\"dateModified\":\"2022-01-03T12:25:07+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/#primaryimage\",\"url\":\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2022\/01\/Affiche-eso-paris-fumeurs-scaled.jpg\",\"contentUrl\":\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2022\/01\/Affiche-eso-paris-fumeurs-scaled.jpg\",\"width\":1810,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/escaudacienne.fr\/esc\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eso Clinique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/escaudacienne.fr\/esc\/#website\",\"url\":\"https:\/\/escaudacienne.fr\/esc\/\",\"name\":\"ESC - Entente Sportive Caudacienne\u00ae\",\"description\":\"Faire du Sport \u00e0 La Queue-en-Brie... c&#039;est facile avec l&#039;E.S.C.\u00ae !\",\"publisher\":{\"@id\":\"https:\/\/escaudacienne.fr\/esc\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/escaudacienne.fr\/esc\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/escaudacienne.fr\/esc\/#organization\",\"name\":\"E.S.C.\u00ae - Entente Sportive Caudacienne\u00ae\",\"url\":\"https:\/\/escaudacienne.fr\/esc\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/escaudacienne.fr\/esc\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2021\/01\/Logo-ESC\u00ae-Rouge-Blanc-1968-5x5-1.png\",\"contentUrl\":\"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2021\/01\/Logo-ESC\u00ae-Rouge-Blanc-1968-5x5-1.png\",\"width\":591,\"height\":591,\"caption\":\"E.S.C.\u00ae - Entente Sportive Caudacienne\u00ae\"},\"image\":{\"@id\":\"https:\/\/escaudacienne.fr\/esc\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ententesportivecaudacienne\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/escaudacienne.fr\/esc\/#\/schema\/person\/829f2ee7197e9e983e17b2c0556f8a77\",\"name\":\"maya2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/escaudacienne.fr\/esc\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f3c0e7be19880464485f1e69bd76ac0ec826e6cb722322e5013cefb2b9de166c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f3c0e7be19880464485f1e69bd76ac0ec826e6cb722322e5013cefb2b9de166c?s=96&d=mm&r=g\",\"caption\":\"maya2\"},\"url\":\"https:\/\/escaudacienne.fr\/esc\/author\/maya2\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Eso Clinique - ESC - Entente Sportive Caudacienne\u00ae","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/","og_locale":"fr_FR","og_type":"article","og_title":"Eso Clinique","og_url":"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/","og_site_name":"ESC - Entente Sportive Caudacienne\u00ae","article_publisher":"https:\/\/www.facebook.com\/ententesportivecaudacienne","article_published_time":"2022-01-03T12:16:14+00:00","article_modified_time":"2022-01-03T12:25:07+00:00","og_image":[{"width":1810,"height":2560,"url":"http:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2022\/01\/Affiche-eso-paris-fumeurs-scaled.jpg","type":"image\/jpeg"}],"author":"maya2","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"maya2"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/#article","isPartOf":{"@id":"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/"},"author":{"name":"maya2","@id":"https:\/\/escaudacienne.fr\/esc\/#\/schema\/person\/829f2ee7197e9e983e17b2c0556f8a77"},"headline":"Eso Clinique","datePublished":"2022-01-03T12:16:14+00:00","dateModified":"2022-01-03T12:25:07+00:00","mainEntityOfPage":{"@id":"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/"},"wordCount":31,"commentCount":0,"publisher":{"@id":"https:\/\/escaudacienne.fr\/esc\/#organization"},"image":{"@id":"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/#primaryimage"},"thumbnailUrl":"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2022\/01\/Affiche-eso-paris-fumeurs-scaled.jpg","articleSection":["Partenaires","Sport-Sant\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/","url":"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/","name":"Eso Clinique - ESC - Entente Sportive Caudacienne\u00ae","isPartOf":{"@id":"https:\/\/escaudacienne.fr\/esc\/#website"},"primaryImageOfPage":{"@id":"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/#primaryimage"},"image":{"@id":"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/#primaryimage"},"thumbnailUrl":"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2022\/01\/Affiche-eso-paris-fumeurs-scaled.jpg","datePublished":"2022-01-03T12:16:14+00:00","dateModified":"2022-01-03T12:25:07+00:00","breadcrumb":{"@id":"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/#primaryimage","url":"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2022\/01\/Affiche-eso-paris-fumeurs-scaled.jpg","contentUrl":"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2022\/01\/Affiche-eso-paris-fumeurs-scaled.jpg","width":1810,"height":2560},{"@type":"BreadcrumbList","@id":"http:\/\/escaudacienne.fr\/esc\/eso-clinique-17\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/escaudacienne.fr\/esc\/"},{"@type":"ListItem","position":2,"name":"Eso Clinique"}]},{"@type":"WebSite","@id":"https:\/\/escaudacienne.fr\/esc\/#website","url":"https:\/\/escaudacienne.fr\/esc\/","name":"ESC - Entente Sportive Caudacienne\u00ae","description":"Faire du Sport \u00e0 La Queue-en-Brie... c&#039;est facile avec l&#039;E.S.C.\u00ae !","publisher":{"@id":"https:\/\/escaudacienne.fr\/esc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/escaudacienne.fr\/esc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/escaudacienne.fr\/esc\/#organization","name":"E.S.C.\u00ae - Entente Sportive Caudacienne\u00ae","url":"https:\/\/escaudacienne.fr\/esc\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/escaudacienne.fr\/esc\/#\/schema\/logo\/image\/","url":"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2021\/01\/Logo-ESC\u00ae-Rouge-Blanc-1968-5x5-1.png","contentUrl":"https:\/\/escaudacienne.fr\/esc\/wp-content\/uploads\/sites\/2\/2021\/01\/Logo-ESC\u00ae-Rouge-Blanc-1968-5x5-1.png","width":591,"height":591,"caption":"E.S.C.\u00ae - Entente Sportive Caudacienne\u00ae"},"image":{"@id":"https:\/\/escaudacienne.fr\/esc\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ententesportivecaudacienne"]},{"@type":"Person","@id":"https:\/\/escaudacienne.fr\/esc\/#\/schema\/person\/829f2ee7197e9e983e17b2c0556f8a77","name":"maya2","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/escaudacienne.fr\/esc\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f3c0e7be19880464485f1e69bd76ac0ec826e6cb722322e5013cefb2b9de166c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f3c0e7be19880464485f1e69bd76ac0ec826e6cb722322e5013cefb2b9de166c?s=96&d=mm&r=g","caption":"maya2"},"url":"https:\/\/escaudacienne.fr\/esc\/author\/maya2\/"}]}},"_links":{"self":[{"href":"https:\/\/escaudacienne.fr\/esc\/wp-json\/wp\/v2\/posts\/13396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/escaudacienne.fr\/esc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/escaudacienne.fr\/esc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/escaudacienne.fr\/esc\/wp-json\/wp\/v2\/users\/1970"}],"replies":[{"embeddable":true,"href":"https:\/\/escaudacienne.fr\/esc\/wp-json\/wp\/v2\/comments?post=13396"}],"version-history":[{"count":3,"href":"https:\/\/escaudacienne.fr\/esc\/wp-json\/wp\/v2\/posts\/13396\/revisions"}],"predecessor-version":[{"id":13401,"href":"https:\/\/escaudacienne.fr\/esc\/wp-json\/wp\/v2\/posts\/13396\/revisions\/13401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/escaudacienne.fr\/esc\/wp-json\/wp\/v2\/media\/13397"}],"wp:attachment":[{"href":"https:\/\/escaudacienne.fr\/esc\/wp-json\/wp\/v2\/media?parent=13396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/escaudacienne.fr\/esc\/wp-json\/wp\/v2\/categories?post=13396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/escaudacienne.fr\/esc\/wp-json\/wp\/v2\/tags?post=13396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}